{"id":26,"date":"2015-03-25T20:50:12","date_gmt":"2015-03-25T19:50:12","guid":{"rendered":"https:\/\/www.studyhelp.de\/mathe\/wp\/?page_id=26"},"modified":"2019-08-02T14:45:44","modified_gmt":"2019-08-02T12:45:44","slug":"e-funktion","status":"publish","type":"page","link":"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/e-funktion\/","title":{"rendered":"e-Funktion"},"content":{"rendered":"\n<p>Die e-Funktion geh\u00f6rt zur Gruppe der Exponentialfunktionen und wird auch &#8222;nat\u00fcrliche Exponentialfunktion&#8220; genannt. Um die e-Funktion zu verstehen, schauen wir uns in diesem Artikel alle Themen an, die du f\u00fcr die Rechnung mit der e-Funktion ben\u00f6tigst.<\/p>\n<p><strong>Inhaltsverzeichnis<\/strong><\/p>\n<ul>\n<li><a href=\"#grundlagen-exponentialfunktion\">Grundlagen Exponentialfunktion<\/a><\/li>\n<li><a href=\"#rechnen-mit-der-e-funktion\">Rechnen mit der e-Funktion<\/a><\/li>\n<li><a href=\"#ableiten-der-exponentialfunktion\">Ableiten der Exponentialfunktion<\/a><\/li>\n<li><a href=\"#integrieren-der-e-funktion\">Integrieren der e-Funktion<\/a><\/li>\n<li><a href=\"#symmetrie-der-e-funktion\">Symmetrieverhalten<\/a><\/li>\n<li><a href=\"#grenzverhalten-der-e-funktion\">Grenzverhalten<\/a><\/li>\n<li><a href=\"#steckbriefaufgaben-e-funktion\">Steckbriefaufgaben mit e-Funktion<\/a><\/li>\n<\/ul>\n\n<hr>\n<h2 class=\"anchor\" id=\"grundlagen-exponentialfunktion\">Grundlagen Exponentialfunktion <\/h2>\n<p>Eine Funktion hei\u00dft Exponentialfunktion (zur Basis b), wenn sie die Form<\/p>\n<p>\\begin{align*}<br \/>\nf(x) = b^x,<br \/>\n\\end{align*}<\/p>\n<p>aufweist, wobei b eine beliebige positive Konstante bezeichnet. <\/p>\n<p><strong>Falls b=e ist, spricht man im Allgemeinen von &#8222;der&#8220; e-Funktion.<\/strong><\/p>\n<p>Bitte lasst euch nicht von diesem &#8222;e&#8220; verwirren. Es handelt sich hierbei um die eulersche Zahl &#8211; eine ganz normale Zahl e = 2,718281828459045235.. . Die Form der Exponentialfunktion erinnert uns an die des Potenzausdrucks, wobei hier die Rolle von Basis und Exponent vertauscht wird!<\/p>\n<p>Hier k\u00f6nnen wir also nicht wie gewohnt ableiten und m\u00fcssen den Ausdruck f\u00fcr Ableitungszwecke umschreiben. <\/p>\n<p><strong>Es gilt:<\/strong><br \/>\n\\begin{align*}<br \/>\nb^x = e^{\\ln(b)\\cdot x}<br \/>\n\\end{align*}<\/p>\n<p>F\u00fcr den Fall das b=e ist, gilt als Folge der Potenzgesetze f\u00fcr die e-Funktion:<\/p>\n<p>\\begin{align*}<br \/>\ne^0=1, \\ \\ e^1=e, \\ \\ e^x \\cdot e^y = e^{x+y}<br \/>\n\\end{align*}<\/p>\n<p>Hier seht ihr den Graphen der e-Funktion<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-3149 size-medium\" src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/bil_exponentialfunktion_neu-300x196.png\" alt=\"e-Funktion e^x\" width=\"300\" height=\"196\" srcset=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/bil_exponentialfunktion_neu-300x196.png 300w, https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/bil_exponentialfunktion_neu-768x501.png 768w, https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/bil_exponentialfunktion_neu.png 893w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Wie ihr sehen k\u00f6nnt verl\u00e4uft der Graph der e-Funktion immer oberhalb der x-Achse. Der Graph n\u00e4hert sich zwar der x-Achse an, wird diese aber nicht schneiden. Dies bedeutet wiederum, dass die klassische e-Funktion keine Nullstellen besitzt. <\/p>\n<p>Der streng monoton steigende verlauf der Funktion schneidet die y-Achse im punkt (0|1).<\/p>\n<p><strong>Thema e-Funktion noch nicht verstanden? Schaut euch die Einleitung von Daniel zu dem Thema an!<\/strong><\/p>\n<div class=\"lyte-wrapper\" title=\"e-Funktion, Kurvendiskussion, &Uuml;bersicht 1, Mathe online | Mathe by Daniel Jung\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_gDb3k0XfLec\"><div id=\"lyte_gDb3k0XfLec\" data-src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FgDb3k0XfLec%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">e-Funktion, Kurvendiskussion, \u00dcbersicht 1, Mathe online | Mathe by Daniel Jung<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/gDb3k0XfLec\" rel=\"nofollow\"><img src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FgDb3k0XfLec%2F0.jpg\" alt=\"e-Funktion, Kurvendiskussion, &Uuml;bersicht 1, Mathe online | Mathe by Daniel Jung\" width=\"420\" height=\"216\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px;\"><\/div><br \/>\n<\/p>\n<h2 class=\"anchor\" id=\"rechnen-mit-der-e-funktion\">Rechnen mit der e-Funktion<\/strong><\/h2>\n<p>Zur L\u00f6sung von e-Funktionen verwendet man in der Regel ihre Umkehrfunktion, den <a href=\"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/ln-funktion\/\" target=\"_blank\" rel=\"noopener noreferrer\">nat\u00fcrlichen Logarithmus<\/a> ln. <\/p>\n<p>Ein n\u00fctzlicher Zusammenhang ist<\/p>\n<p>\\begin{align*}<br \/>\ne^{\\ln(x)} = x \\quad \\textrm{bzw.} \\quad \\ln(e^x)=x.<br \/>\n\\end{align*}<\/p>\n<p>Achtet auf die Logarithmengesetze! Es folgen einige <strong>Beispiele<\/strong> zum L\u00f6sen e-Funktionen:<\/p>\n<p>\\begin{align*}<br \/>\ne^{2x}\\cdot (x^2-2) = 0  \\\\<br \/>\ne^{2x}= 0 \\\u00a0 \\vee \\ x^2-2&amp;=0 \\quad |+2 \\\\<br \/>\nx^2&amp;=2 \\quad |\\sqrt{ ~~}  \\\\<br \/>\nx_1=\\sqrt{2} &amp;\\wedge x_2=-\\sqrt{2}<br \/>\n\\end{align*}<\/p>\n<p>Warum bringt $e^{2x}= 0$ keine L\u00f6sung? Wenn man beide Seite logarithmiert folgt $\\ln(2x)=\\ln(0)$. Da der nat\u00fcrliche Logarithmus aber f\u00fcr 0 nicht definiert ist ($D=(0,\\infty))$, gibt es keine L\u00f6sung.<\/p>\n<div class=\"box exercise\">\n<h3>Beispiele<\/h3>\n<p>\\begin{align*}<br \/>\n1. \\quad 8e^{-2x}-16&amp;=0 \\quad\\quad \\quad \\ \\mid+16 \\\\<br \/>\n8e^{-2x} &amp;= 16 \\quad \\quad \\ \\ \\mid:8  \\\\<br \/>\ne^{-2x}&amp;=2 \\quad \\quad \\ \\quad | \\ln \\\\<br \/>\n\\ln(e^{-2x})&amp;=\\ln(2) \\\\<br \/>\n-2 x&amp;= \\ln(2) \\quad \\quad |:(-2) \\\\<br \/>\nx&amp;= -\\ln(2)\/2<br \/>\n\\end{align*}<\/p>\n<p>\\begin{align*}<br \/>\n2. \\quad 4e^{3x}-e^{2x}&amp;=0 \\quad \\quad \\quad|+e^{2x}  \\\\<br \/>\n4e^{3x} &amp;= e^{2x} \\quad \\quad \\ | \\ln \\\\<br \/>\n\\ln(4 \\cdot e^{3x})&amp;=\\ln(e^{2x}) \\\\<br \/>\n\\ln(4)+\\ln(e^{3x})&amp;=2x \\\\<br \/>\n\\ln(4)+3x&amp;=2x \\\\<br \/>\n\\ln(4)&amp;=-x \\\\<br \/>\n-\\ln(4)&amp;=x<br \/>\n\\end{align*}<\/p>\n<\/div>\n<p><strong>Schau dir zur Wiederholung die komplette Playlist zum Thema Exponentialsfunktion an!<\/strong><\/p>\n<div class=\"lyte-wrapper\" title=\"Gleichungen l&ouml;sen bei e^x, &Uuml;bersicht 1, e-Funktion | Mathe by Daniel Jung\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_Yj2USfj4gDo\"><div id=\"lyte_Yj2USfj4gDo\" data-src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FYj2USfj4gDo%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">Gleichungen l\u00f6sen bei e^x, \u00dcbersicht 1, e-Funktion | Mathe by Daniel Jung<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/Yj2USfj4gDo\" rel=\"nofollow\"><img src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FYj2USfj4gDo%2F0.jpg\" alt=\"Gleichungen l&ouml;sen bei e^x, &Uuml;bersicht 1, e-Funktion | Mathe by Daniel Jung\" width=\"420\" height=\"216\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px;\"><\/div><\/p>\n<h2 class=\"anchor\" id=\"ableiten-der-exponentialfunktion\">Ableiten der Exponentialfunktion<\/h2>\n<p>Eine e-Funktion wird folgenderma\u00dfen abgeleitet: Ihr verwendet &#8222;offiziell&#8220; die Kettenregel, aber es geht eigentlich um einiges einfacher. Wir betrachten daf\u00fcr die Funktion<\/p>\n<p>\\begin{align*}<br \/>\nf(x)= e^{5x},<br \/>\n\\end{align*}<\/p>\n<p>welche wir nach x ableiten wollen. Daf\u00fcr schreiben wir einfach den Term mit der e-Funktion nochmal hin und multiplizieren das Ding mit dem abgeleiteten Exponenten. Der Exponent ist hier 5x und abgeleitet w\u00e4re das einfach 5. Dann folgt f\u00fcr die Ableitung<\/p>\n<p>\\begin{align*}<br \/>\nf'(x)= e^{5x} \\cdot 5.<br \/>\n\\end{align*}<\/p>\n<div class=\"box exercise\">\n<h3>Weiteres Beispiel<\/h3>\n<p><center>$<br \/>\n\\begin{array}{c|c}<br \/>\nf(x) &amp; f'(x) \\\\ \\hline<br \/>\ne^x &amp; e^x\\\\ \\hline<br \/>\n2e^x &amp; 2e^x \\\\<br \/>\n3e^x &amp; 3e^x \\\\ \\hline<br \/>\ne^{2x} &amp; 2e^{2x}\\\\<br \/>\ne^{3x} &amp; 3e^{3x} \\\\<br \/>\ne^{x^2}&amp; 2xe^{x^2} \\\\<br \/>\ne^{2-4x} &amp; -4e^{2-4x} \\\\ \\hline<br \/>\n20e^{3x} &amp; 3 \\cdot 20 e^{3x} \\\\<br \/>\nx \\cdot e^{2x} &amp; Produktregel \\\\<br \/>\n\\end{array}<br \/>\n$<\/center><br \/>\n<\/div>\n<p>Falls eine e-Funktion mit anderen Funktionen multipliziert wird, m\u00fcssen wir die bereits bekannte Produktregel anwenden. <\/p>\n<p><strong>Wie das geht, k\u00f6nnt ihr euch nochmals in diesem Video anschauen!<\/strong><\/p>\n<div class=\"lyte-wrapper\" title=\"e-Funktion im Produkt ableiten, Produkt- und Kettenregel, Ableitung Exponentialfunktion\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_6hWdotlWa5U\"><div id=\"lyte_6hWdotlWa5U\" data-src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F6hWdotlWa5U%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">e-Funktion im Produkt ableiten, Produkt- und Kettenregel, Ableitung Exponentialfunktion<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/6hWdotlWa5U\" rel=\"nofollow\"><img src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F6hWdotlWa5U%2F0.jpg\" alt=\"e-Funktion im Produkt ableiten, Produkt- und Kettenregel, Ableitung Exponentialfunktion\" width=\"420\" height=\"216\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px;\"><\/div><br \/>\n<\/p>\n<div class=\"box exercise\">\n<h3>Weiteres Beispiel<\/h3>\n<p>\\begin{align*}<br \/>\nf(x)&amp;= \\underbrace{(x^2-2)}_{\\text{u(x)}} \\cdot \\underbrace{e^{-2x}}_{\\text{v(x)}}  \\\\<br \/>\n\\textrm{mit} \\quad u(x)&amp;=x^2-2 \\quad u'(x)=2x  \\\\<br \/>\n\\textrm{und} \\quad v(x)&amp;=e^{-2x} \\quad \\quad v'(x)= -2e^{-2x}<br \/>\n\\end{align*}<\/p>\n<p>Somit ergibt sich f\u00fcr die erste Ableitung:<\/p>\n<p>\\begin{align*}<br \/>\nf'(x)=2xe^{-2x}+(x^2-2) \\cdot (-2e^{-2x})<br \/>\n\\end{align*}<\/p>\n<p>Wer m\u00f6chte, kann diesen Ausdruck jetzt noch etwas umschreiben:<\/p>\n<p>\\begin{align*}<br \/>\nf'(x) &amp;= e^{-2x} (2x+(x^2-2)(-2))  \\\\<br \/>\n&amp;=e^{-2x}(2x-2x^2+4)  \\\\<br \/>\n&amp;=e^{-2x}(-2x^2+2x+4)<br \/>\n\\end{align*}<br \/>\n<\/div>\n<p><strong> Daniel zeigt euch im Video, wie ihr die Exponentialfunktion ableiten k\u00f6nnt<\/strong><\/p>\n<div class=\"lyte-wrapper\" title=\"Exponentialfunktion ableiten, Ableitung e-Funktion, einfache &Uuml;bersicht | Mathe by Daniel Jung\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_9Dj8deA2XLw\"><div id=\"lyte_9Dj8deA2XLw\" data-src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F9Dj8deA2XLw%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">Exponentialfunktion ableiten, Ableitung e-Funktion, einfache \u00dcbersicht | Mathe by Daniel Jung<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/9Dj8deA2XLw\" rel=\"nofollow\"><img src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2F9Dj8deA2XLw%2F0.jpg\" alt=\"Exponentialfunktion ableiten, Ableitung e-Funktion, einfache &Uuml;bersicht | Mathe by Daniel Jung\" width=\"420\" height=\"216\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px;\"><\/div><br \/>\n<\/p>\n<h2 class=\"anchor\" id=\"integrieren-der-e-funktion\">Integrieren der e-Funktion<\/h2>\n<p>\\begin{array}{c|c}<br \/>\nf(x) &amp; F(x) \\\\ \\hline<br \/>\ne^x &amp; e^x\\\\<br \/>\ne^{2x} &amp; \\frac{1}{2}e^{2x} \\\\<br \/>\ne^{3x} &amp; \\frac{1}{3}e^{3x} \\\\<br \/>\ne^{4-2x} &amp; \\frac{-1}{2}e^{4-2x} \\\\<br \/>\n20e^{10x} &amp; \\frac{20}{10}e^{10x} \\\\<br \/>\n3e^{5-2x} &amp; \\frac{3}{-2}e^{5-2x} \\\\<br \/>\ne^{x^2}, e^{x^3} &amp;\\textrm{Geht nicht!} \\\\ \\<br \/>\n2x\\cdot e^{-2x} &amp; \\textrm{Partielle Integration} \\\\<br \/>\n2x\\cdot e^{x^2} &amp; \\textrm{Substitution}\u00a0 \\\\<br \/>\n\\end{array}<\/p>\n<p>Egal ob <a href=\"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/nullstellen-berechnen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nullstellen bestimmen<\/a>, Ableitung oder Stammfunktion bilden: Achtet auf die Struktur der Funktion! Steht da nur eine Summe oder Differenz, ist ein Produkt aus Term mit einer Variablen mal e hoch irgendwas zu erkennen?<\/p>\n<p><strong>Schau dir zur Vertiefung Daniels Lernvideo zum Thema Stammfunktion bei e-Funktion an.<\/strong><\/p>\n<div class=\"lyte-wrapper\" title=\"Stammfunktion e^x &Uuml;bersicht, e-Funktion, Integrationsm&ouml;glichkeiten | Mathe by Daniel Jung\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_Xn9ZV_mMZJ0\"><div id=\"lyte_Xn9ZV_mMZJ0\" data-src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FXn9ZV_mMZJ0%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">Stammfunktion e^x \u00dcbersicht, e-Funktion, Integrationsm\u00f6glichkeiten | Mathe by Daniel Jung<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/Xn9ZV_mMZJ0\" rel=\"nofollow\"><img src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FXn9ZV_mMZJ0%2F0.jpg\" alt=\"Stammfunktion e^x &Uuml;bersicht, e-Funktion, Integrationsm&ouml;glichkeiten | Mathe by Daniel Jung\" width=\"420\" height=\"216\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px;\"><\/div><\/p>\n<h2 class=\"anchor\" id=\"symmetrie-der-e-funktion\">Symmetrie der e-Funktion<\/h2>\n<p>Ist $f(x)=x^2\\cdot e^{-x^2}$ achsensymmetrisch zur y-Achse? Dann m\u00fcsste gelten:<\/p>\n<p>\\begin{align*}<br \/>\nf(-x)&amp;=f(x) \\\\<br \/>\n(-x)^2\\cdot e^{-(-x)^2} &amp;= x^2\\cdot e^{-x^2} \\\\<br \/>\nx^2\\cdot e^{-x^2} &amp;= x^2\\cdot e^{-x^2} \\\u00a0<br \/>\n\\end{align*}<\/p>\n<p>Ist $f(x)=-10x \\cdot e^{x^2}$ punktsymmetrisch zum Ursprung? Dann m\u00fcsste gelten:<\/p>\n<p>\\begin{align*}<br \/>\nf(-x)&amp;=-f(x) \\\\<br \/>\n-10 \\cdot (-x) \\cdot e^{(-x)^2} &amp;= -\\left(-10x \\cdot e^{x^2} \\right) \\\\<br \/>\n10 x \\cdot e^{x^2} &amp;= 10x \\cdot e^{x^2} \\\u00a0<br \/>\n\\end{align*}<\/p>\n<p><strong>Schau dir Daniels Lernvideo zum Thema Symmetrie an.<\/strong><\/p>\n<div class=\"lyte-wrapper\" title=\"Symmetrie bei e-Funktionen, Exponentialfunktion, Mathehilfe online | Mathe by Daniel Jung\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_M5Kv6oo2an0\"><div id=\"lyte_M5Kv6oo2an0\" data-src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FM5Kv6oo2an0%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">Symmetrie bei e-Funktionen, Exponentialfunktion, Mathehilfe online | Mathe by Daniel Jung<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/M5Kv6oo2an0\" rel=\"nofollow\"><img src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FM5Kv6oo2an0%2F0.jpg\" alt=\"Symmetrie bei e-Funktionen, Exponentialfunktion, Mathehilfe online | Mathe by Daniel Jung\" width=\"420\" height=\"216\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px;\"><\/div><\/p>\n<h2 class=\"anchor\" id=\"grenzverhalten-der-e-funktion\">Grenzverhalten der e-Funktion<\/h2>\n<p>Exponentialfunktionen und ihre Graphen werden auf dieselbe Weise untersucht wie ganzrationale Funktionen. Nur das Verhalten<br \/>\neiner Exponentialfunktion f\u00fcr $x \\to + \\infty$ und f\u00fcr $x \\to &#8211; \\infty$ wird durch andere Regeln beherrscht.<\/p>\n<ul>\n<li>F\u00fcr $x \\to + \\infty$ strebt $e^x \\to + \\infty$.<\/li>\n<li>F\u00fcr $x \\to -\\infty$ strebt $e^x \\to 0$, d.h. die x-Achse ist die Asymptote des Graphen von f mit $f(x)=e^x$.<\/li>\n<\/ul>\n<p>Dar\u00fcber hinaus gilt f\u00fcr $n \\geq 1$:<\/p>\n<ul>\n<li>F\u00fcr $x \\to + \\infty$ strebt $x^n \\cdot e^x \\to + \\infty$.<\/li>\n<li>F\u00fcr $x \\to &#8211; \\infty$ strebt $x^n \\cdot e^x \\to 0$, d.h. die x-Achse ist die Asymptote des Graphen von f mit $f(x)=x^n \\cdot e^x$.<\/li>\n<\/ul>\n<div class=\"box exercise\">\n<h3>Beispiel 1<\/h3>\n<p>$f(x)=(x^2-1)e^{-2x}$<\/p>\n<p>\\begin{align*}<br \/>\n\\lim_{x \\to +\\infty} \\quad \\underbrace{(x^2-1)}_{\\rightarrow +\\infty} \\cdot \\underbrace{e^{-2x}}_{\\rightarrow 0} \\quad &amp;\\rightarrow 0 \\\\ \\\\<br \/>\n\\lim_{x \\to -\\infty} \\quad \\underbrace{(x^2-1)}_{\\rightarrow +\\infty} \\cdot \\underbrace{e^{-2x}}_{\\rightarrow +\\infty} \\quad &amp;\\rightarrow +\\infty<br \/>\n\\end{align*}<\/p>\n<p>Merkt euch: Bei der Betrachtung des Grenzverhaltens orientieren wir uns an der e-Funktion &#8211; die am st\u00e4rksten wachsende Funktion.<\/p>\n<h3>Beispiel 2<\/h3>\n<p>Betrachten wir den Graph von $f(x)=(x^2-1)e^{-2x}$, best\u00e4tigt sich unsere Grenzwertberechnung.<\/p>\n<ul>\n<li>lassen wir x gegen $-\\infty$ laufen, strebt die Funktion gegen +$\\infty$<\/li>\n<li>lassen wir x gegen $\\infty$ laufen, strebt die Funktion gegen 0, somit ist die x-Achse Asymptote<\/li>\n<\/ul>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-1182 size-medium\" src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/studyhelp48-300x121.png\" alt=\"e-funktion Grenzverhalten\" width=\"300\" height=\"121\" srcset=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/studyhelp48-300x121.png 300w, https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/studyhelp48-768x310.png 768w, https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/studyhelp48.png 796w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<\/div>\n<p><strong>Daniel erkl\u00e4rt dir das Grenzverhalten bei einer e-Funktion nochmal in seinem Lernvideo<\/strong>.<\/p>\n<div class=\"lyte-wrapper\" title=\"Grenzverhalten bei e-Funktionen, Limes-Schreibweise bei e hoch x | Mathe by Daniel Jung\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_RAfYXqWz8Ko\"><div id=\"lyte_RAfYXqWz8Ko\" data-src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FRAfYXqWz8Ko%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">Grenzverhalten bei e-Funktionen, Limes-Schreibweise bei e hoch x | Mathe by Daniel Jung<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/RAfYXqWz8Ko\" rel=\"nofollow\"><img src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FRAfYXqWz8Ko%2F0.jpg\" alt=\"Grenzverhalten bei e-Funktionen, Limes-Schreibweise bei e hoch x | Mathe by Daniel Jung\" width=\"420\" height=\"216\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px;\"><\/div><\/p>\n<h2 class=\"anchor\" id=\"steckbriefaufgaben-e-funktion\">Steckbriefaufgaben mit e-Funktion<\/h2>\n<p>Denkt an die Schritte bei Steckbriefaufgaben. Es kann sein, dass die gesuchte Funktion die Form<\/p>\n<p>\\begin{align*}<br \/>\nf(x)=a\\cdot e^{-kx}<br \/>\n\\end{align*}<\/p>\n<p>aufweisen soll. Es liegen somit zwei Unbekannte vor und die Aufgabe m\u00fcsste zwei Bedingungen hergeben. In unserem Beispiel sollen die Funktion durch die Punkte P(2|4) und Q(5|200) gehen. Wir stellen somit unser Gleichungssystem auf<\/p>\n<p>\\begin{align*}<br \/>\n\\text{I}&amp; \\quad \\quad 4=a \\cdot e^{-2k}  \\\\<br \/>\n\\text{II}&amp; \\quad 200= a\\cdot e^{-5k}<br \/>\n\\end{align*}<\/p>\n<p>und l\u00f6sen es nach den Unbekannten a und k auf. M\u00f6glichkeit: Gleichung $\\text{I}$ nach a umstellen und in $\\text{II}$ einsetzen. Wir erhalten dann f\u00fcr k=-1,3 und a=0,6 und damit die gesuchte Funktion:<\/p>\n<p>\\begin{align*}<br \/>\nf(x)= 0,6 \\cdot e^{1,3\\cdot x}<br \/>\n\\end{align*}<\/p>\n<p>Ein einfaches Beispiel w\u00e4re, wenn die gesuchte Funktion die Form<\/p>\n<p>\\begin{align*}<br \/>\nf(x)=4\\cdot e^{-kx}<br \/>\n\\end{align*}<\/p>\n<p>aufweist und durch den Punkt P(2|10) soll. Warum einfacher? Weil es nur eine Unbekannte k gibt.<\/p>\n\n<p><strong>Wie man eine e-Funktion mittels 2 Punkte aufstellt, zeigt dir Daniel hier in seinem Lernvideo.<\/strong><\/p>\n<div class=\"lyte-wrapper\" title=\"Aufstellen Exponentialfunktion mittels 2 Punkten, e-Funktion | Mathe by Daniel Jung\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_elSwADaCBBQ\"><div id=\"lyte_elSwADaCBBQ\" data-src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FelSwADaCBBQ%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">Aufstellen Exponentialfunktion mittels 2 Punkten, e-Funktion | Mathe by Daniel Jung<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/elSwADaCBBQ\" rel=\"nofollow\"><img src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FelSwADaCBBQ%2F0.jpg\" alt=\"Aufstellen Exponentialfunktion mittels 2 Punkten, e-Funktion | Mathe by Daniel Jung\" width=\"420\" height=\"216\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px;\"><\/div><\/p>\n<p><strong>Weitere Vertiefungsvideos findest du in Daniels Playlist zum Thema e-Funktion!<\/strong><\/p>\n<div class=\"lyte-wrapper\" title=\"Playlist: e-Funktion, die besondere Exponentialfunktion, Eulerfunktion, Analysis\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe playlist\" id=\"WYL_PLLTAHuUj-zHj35XQ7P92WnKgfvRVvGQ3D\"><div id=\"lyte_PLLTAHuUj-zHj35XQ7P92WnKgfvRVvGQ3D\" data-src=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FxRftyh3kC_Q%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">Playlist: e-Funktion, die besondere Exponentialfunktion, Eulerfunktion, Analysis<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtube.com\/playlist?list=PLLTAHuUj-zHj35XQ7P92WnKgfvRVvGQ3D\" rel=\"nofollow\"><br \/>Diese Wiedergabeliste auf YouTube ansehen<\/a><\/noscript><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die e-Funktion geh\u00f6rt zur Gruppe der Exponentialfunktionen und wird auch &#8222;nat\u00fcrliche Exponentialfunktion&#8220; genannt. Um die e-Funktion zu verstehen, schauen wir uns in diesem Artikel alle Themen an, die du f\u00fcr die Rechnung mit der e-Funktion ben\u00f6tigst. Inhaltsverzeichnis Grundlagen Exponentialfunktion Rechnen mit der e-Funktion Ableiten der Exponentialfunktion Integrieren der e-Funktion Symmetrieverhalten Grenzverhalten Steckbriefaufgaben mit e-Funktion Grundlagen [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":6291,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"categories":[15],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>e-Funktion Erkl\u00e4rung und Beispiele - StudyHelp<\/title>\n<meta name=\"description\" content=\"Du ben\u00f6tigst Hilfe bei der e-Funktion? Wir zeigen dir, wie man Exponentialfunktionen berechnet. Hier findest du Beispiele und Lernvideos zur e-Funktion.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/e-funktion\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"e-Funktion Erkl\u00e4rung und Beispiele - StudyHelp\" \/>\n<meta property=\"og:description\" content=\"Du ben\u00f6tigst Hilfe bei der e-Funktion? Wir zeigen dir, wie man Exponentialfunktionen berechnet. Hier findest du Beispiele und Lernvideos zur e-Funktion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/e-funktion\/\" \/>\n<meta property=\"og:site_name\" content=\"StudyHelp Online-Lernen\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-02T12:45:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/bil_exponentialfunktion_neu-300x196.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.studyhelp.de\/online-lernen\/#website\",\"url\":\"https:\/\/www.studyhelp.de\/online-lernen\/\",\"name\":\"StudyHelp Online-Lernen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.studyhelp.de\/online-lernen\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/e-funktion\/#primaryimage\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/www.studyhelp.de\/online-lernen\/wp-content\/uploads\/2015\/03\/bil_exponentialfunktion_neu.png\",\"width\":893,\"height\":583},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/e-funktion\/#webpage\",\"url\":\"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/e-funktion\/\",\"name\":\"e-Funktion Erkl\\u00e4rung und Beispiele - StudyHelp\",\"isPartOf\":{\"@id\":\"https:\/\/www.studyhelp.de\/online-lernen\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/e-funktion\/#primaryimage\"},\"datePublished\":\"2015-03-25T19:50:12+00:00\",\"dateModified\":\"2019-08-02T12:45:44+00:00\",\"description\":\"Du ben\\u00f6tigst Hilfe bei der e-Funktion? Wir zeigen dir, wie man Exponentialfunktionen berechnet. Hier findest du Beispiele und Lernvideos zur e-Funktion.\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.studyhelp.de\/online-lernen\/mathe\/e-funktion\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/pages\/26"}],"collection":[{"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":35,"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/pages\/26\/revisions"}],"predecessor-version":[{"id":14347,"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/pages\/26\/revisions\/14347"}],"up":[{"embeddable":true,"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/pages\/6291"}],"wp:attachment":[{"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studyhelp.de\/online-lernen\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}